{"id":5711,"date":"2022-09-19T14:42:06","date_gmt":"2022-09-19T12:42:06","guid":{"rendered":"https:\/\/www.tarugoconf.com\/blog\/?p=5711"},"modified":"2022-09-22T08:58:16","modified_gmt":"2022-09-22T06:58:16","slug":"brella-en-que-consiste-como-se-usa-y-quien-lo-puede-usar","status":"publish","type":"post","link":"https:\/\/www.trgcon.com\/blog\/brella-en-que-consiste-como-se-usa-y-quien-lo-puede-usar\/","title":{"rendered":"Brella: \u00bfEn qu\u00e9 consiste, c\u00f3mo se usa y qui\u00e9n lo puede usar?"},"content":{"rendered":"\n<p>Primero, respondemos a la \u00faltima pregunta. \u00ab\u00bfQui\u00e9n puede acceder a <a href=\"https:\/\/www.brella.io\/?utm_campaign=Brella+brand&amp;utm_term=brella&amp;utm_source=adwords&amp;utm_medium=ppc&amp;hsa_net=adwords&amp;hsa_tgt=kwd-297492089651&amp;hsa_ver=3&amp;hsa_grp=72165457368&amp;hsa_cam=1704978690&amp;hsa_ad=421551344137&amp;hsa_kw=brella&amp;hsa_acc=1687227951&amp;hsa_src=g&amp;hsa_mt=e&amp;gclid=CjwKCAjwpqCZBhAbEiwAa7pXeYqK1SMYllWHBu1EBhl6N4YdNCx_907RdKDnHKFF_5hVTiSWLJzzsxoCY3MQAvD_BwE\" data-type=\"URL\" data-id=\"https:\/\/www.brella.io\/?utm_campaign=Brella+brand&amp;utm_term=brella&amp;utm_source=adwords&amp;utm_medium=ppc&amp;hsa_net=adwords&amp;hsa_tgt=kwd-297492089651&amp;hsa_ver=3&amp;hsa_grp=72165457368&amp;hsa_cam=1704978690&amp;hsa_ad=421551344137&amp;hsa_kw=brella&amp;hsa_acc=1687227951&amp;hsa_src=g&amp;hsa_mt=e&amp;gclid=CjwKCAjwpqCZBhAbEiwAa7pXeYqK1SMYllWHBu1EBhl6N4YdNCx_907RdKDnHKFF_5hVTiSWLJzzsxoCY3MQAvD_BwE\" target=\"_blank\" rel=\"noreferrer noopener\">Brella<\/a>?\u00bb<strong> \u00a1TODO EL MUNDO!<\/strong><\/p>\n\n\n\n<p>Y, os preguntar\u00e9is, \u00ab\u00bfpero si el evento es presencial, para qu\u00e9 lo necesito?\u00bb. Te presentamos por delante todo un post lleno de funcionalidades de Brella. Esta plataforma te permitir\u00e1 <strong>conocer Tarugos maravillosos, agendar reuniones con ellos, visitar stands virtuales de los partners de la #tarugo22 y, \u00a1muchas cosas m\u00e1s!<\/strong><\/p>\n\n\n\n<p>Aunque el COVIDged\u00f3n ya sea cosa del pasado (o no, pero al menos s\u00ed la vida alterada), y la #tarugo22 pueda, por fin, volver a ser presencial, hemos decidido volver a contar con la plataforma de streaming y networking online que hemos estado usando en las \u00faltimas ediciones: Brella.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"488\" src=\"https:\/\/www.tarugoconf.com\/blog\/wp-content\/uploads\/2021\/08\/Brella-homepage-1024x488.png\" alt=\"Home de brella.io\" class=\"wp-image-5549\" srcset=\"https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/Brella-homepage-1024x488.png 1024w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/Brella-homepage-300x143.png 300w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/Brella-homepage-768x366.png 768w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/Brella-homepage.png 1304w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Queremos crear el ambiente m\u00e1s parecido posible a un evento f\u00edsico<\/strong>&nbsp;donde, adem\u00e1s de las charlas, teng\u00e1is ese&nbsp;<em>nosequ\u00e9<\/em>&nbsp;que hace de la TarugoConf un evento tan especial.<\/p>\n\n\n\n<p>Brella nos encant\u00f3 porque nos proporcionaba un entorno donde, adem\u00e1s del streaming, pod\u00edamos&nbsp;<strong>facilitar el networking entre asistentes y patrocinadores<\/strong>, as\u00ed como crear los denominados \u201c<em>virtual booths<\/em>\u201c, los stands virtuales para nuestros sponsors. Eso s\u00ed, lo del pulpo no conseguimos solucionarlo, espero que sep\u00e1is perdon\u00e1rnoslo \ud83d\ude05<\/p>\n\n\n\n<p>Como participante en la #tarugo22 habr\u00e1s recibido un email con un c\u00f3digo y un enlace a Brella como este:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"522\" src=\"https:\/\/www.tarugoconf.com\/blog\/wp-content\/uploads\/2021\/08\/tarugo21-acceder-1024x522.jpg\" alt=\"\" class=\"wp-image-5591\" srcset=\"https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/tarugo21-acceder-1024x522.jpg 1024w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/tarugo21-acceder-300x153.jpg 300w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/tarugo21-acceder-768x391.jpg 768w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/tarugo21-acceder-1536x783.jpg 1536w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/tarugo21-acceder-1568x799.jpg 1568w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/tarugo21-acceder.jpg 1582w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Este enlace incluye el c\u00f3digo exclusivo que podr\u00e1s usar para registrarte en la plataforma. OJO\u2026&nbsp;<strong>el enlace \u00fanico NO est\u00e1 vinculado a la cuenta de correo que compr\u00f3 la entrada y solo se puede usar una vez<\/strong>, as\u00ed que, que no se te ocurra publicarlo en Twitter o compartirlo en el grupo de WhatsApp con los colegas, o lo m\u00e1s probable es que no puedas registrarte si alguien se te adelanta. Si tuvieras cualquier problema al entrar, m\u00e1ndanos un email a&nbsp;<a rel=\"noreferrer noopener\" href=\"mailto:bea@bonillaware.com\" target=\"_blank\">bea@bonillaware.com<\/a>&nbsp;y te ayudaremos a resolverlo.<\/p>\n\n\n\n<p>Usa el enlace en el navegador de tu elecci\u00f3n para acceder a Brella y usa cualquiera de los m\u00e9todos ofrecidos para identificarte. Si ya participaste el a\u00f1o pasado en la #tarugo21 y no eres de las personas que borran las cookies con regularidad lo m\u00e1s normal es que te detecte autom\u00e1ticamente, y si no, introduce tu email para que te recuerde y, de paso, cargue todo lo que ya te molestaste en configurar el a\u00f1o pasado:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"808\" height=\"520\" src=\"https:\/\/www.tarugoconf.com\/blog\/wp-content\/uploads\/2021\/08\/image-4.png\" alt=\"P\u00e1gina de registro de Brella.io. Puedes usar el mismo email que usaste en la #tarugo20 para identificarte.\" class=\"wp-image-5557\" srcset=\"https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/image-4.png 808w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/image-4-300x193.png 300w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/image-4-768x494.png 768w\" sizes=\"auto, (max-width: 808px) 100vw, 808px\" \/><\/figure>\n\n\n\n<p>Si es tu primera vez, no hay problema. Puedes identificarte de cara a Brella de muchas maneras:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"936\" height=\"649\" src=\"https:\/\/www.tarugoconf.com\/blog\/wp-content\/uploads\/2021\/08\/image-2.png\" alt=\"P\u00e1gina de registro de Brella.io. Ofrece identificarse mediante LinkedIn, Google, Apple o Facebook.\" class=\"wp-image-5555\" srcset=\"https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/image-2.png 936w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/image-2-300x208.png 300w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/08\/image-2-768x533.png 768w\" sizes=\"auto, (max-width: 936px) 100vw, 936px\" \/><\/figure>\n\n\n\n<p>Una vez dentro, deber\u00edas ver la siguiente pantalla, con dos o tres opciones dependiendo de si tambi\u00e9n participaste en la edici\u00f3n del a\u00f1o pasado: unirte a un evento o entrar a la Tarugoconf. Si no te sale la opci\u00f3n de la #tarugo22 no te preocupes, pulsa en \u201cJoin New Event\u201d y usa el c\u00f3digo que te hemos enviado por email (lo que va despu\u00e9s de&nbsp;<em>https:\/\/next.brella.io\/join\/<\/em>), autom\u00e1ticamente te vincular\u00e1 con la #tarugo22.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"493\" src=\"https:\/\/www.tarugoconf.com\/blog\/wp-content\/uploads\/2022\/09\/Captura-de-pantalla-2022-09-15-160917-1024x493.png\" alt=\"\" class=\"wp-image-5712\" srcset=\"https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2022\/09\/Captura-de-pantalla-2022-09-15-160917-1024x493.png 1024w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2022\/09\/Captura-de-pantalla-2022-09-15-160917-300x144.png 300w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2022\/09\/Captura-de-pantalla-2022-09-15-160917-768x370.png 768w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2022\/09\/Captura-de-pantalla-2022-09-15-160917-1536x739.png 1536w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2022\/09\/Captura-de-pantalla-2022-09-15-160917-1568x755.png 1568w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2022\/09\/Captura-de-pantalla-2022-09-15-160917.png 1909w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u00a1Y ya estar\u00edas dentro!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"506\" src=\"https:\/\/www.tarugoconf.com\/blog\/wp-content\/uploads\/2022\/09\/Captura-de-pantalla-2022-09-15-161144-1024x506.png\" alt=\"\" class=\"wp-image-5713\" srcset=\"https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2022\/09\/Captura-de-pantalla-2022-09-15-161144-1024x506.png 1024w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2022\/09\/Captura-de-pantalla-2022-09-15-161144-300x148.png 300w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2022\/09\/Captura-de-pantalla-2022-09-15-161144-768x379.png 768w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2022\/09\/Captura-de-pantalla-2022-09-15-161144-1536x758.png 1536w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2022\/09\/Captura-de-pantalla-2022-09-15-161144-1568x774.png 1568w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2022\/09\/Captura-de-pantalla-2022-09-15-161144.png 1843w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Esto es todo por ahora. Si te lo saltas, ya estar\u00edas dentro del evento, as\u00ed que puedes usar el siguiente enlace para saber&nbsp;c\u00f3mo moverte por la #tarugo22.<\/p>\n\n\n\n<p>\u00a1Que lo disfrutes!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primero, respondemos a la \u00faltima pregunta. \u00ab\u00bfQui\u00e9n puede acceder a Brella?\u00bb \u00a1TODO EL MUNDO! Y, os preguntar\u00e9is, \u00ab\u00bfpero si el evento es presencial, para qu\u00e9 lo necesito?\u00bb. Te presentamos por delante todo un post lleno de funcionalidades de Brella. Esta plataforma te permitir\u00e1 conocer Tarugos maravillosos, agendar reuniones con ellos, visitar stands virtuales de los &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.trgcon.com\/blog\/brella-en-que-consiste-como-se-usa-y-quien-lo-puede-usar\/\" class=\"more-link\">Seguir leyendo<span class=\"screen-reader-text\"> \u00abBrella: \u00bfEn qu\u00e9 consiste, c\u00f3mo se usa y qui\u00e9n lo puede usar?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5711","post","type-post","status-publish","format-standard","hentry","category-uncategorized","entry"],"_links":{"self":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/5711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/comments?post=5711"}],"version-history":[{"count":3,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/5711\/revisions"}],"predecessor-version":[{"id":5748,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/5711\/revisions\/5748"}],"wp:attachment":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/media?parent=5711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/categories?post=5711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/tags?post=5711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}