{"id":5615,"date":"2021-09-15T11:10:58","date_gmt":"2021-09-15T09:10:58","guid":{"rendered":"https:\/\/www.tarugoconf.com\/blog\/?p=5615"},"modified":"2021-09-15T11:18:21","modified_gmt":"2021-09-15T09:18:21","slug":"tarugobreakers-tarugo21","status":"publish","type":"post","link":"https:\/\/www.trgcon.com\/blog\/tarugobreakers-tarugo21\/","title":{"rendered":"Los Tarugobreakers de la #Tarugo21"},"content":{"rendered":"\n<p>Utilizaremos la plataforma <a rel=\"noreferrer noopener\" href=\"https:\/\/gatheround.com\/\" target=\"_blank\">Gatheround<\/a>, una especie de <em>Chat Roulette <\/em>para eventos que <strong>os emparejar\u00e1 de forma aleatoria con otros asistentes en reuniones 1:1 en las que se os sugerir\u00e1n temas constantemente<\/strong> como, por ejemplo, \u201c\u00bfcu\u00e1l es tu serie favorita?\u201d o \u201c\u00bfWozniak o Jobs?\u201d, para que nunca os qued\u00e9is sin saber de qu\u00e9 hablar.<\/p>\n\n\n\n<p>Para ello, debes darte de alta ASAP en la p\u00e1gina de la Tarugo en Icebreaker (tienes los enlaces a cada una de las rondas m\u00e1s adelante). \u00bfPor qu\u00e9 lo antes posible? Porque tenemos un l\u00edmite de 200 participantes en el juego AL MISMO TIEMPO.<\/p>\n\n\n\n<p>El Icebreaker de la Tarugo constar\u00e1 de tres rondas de 30 minutos cada una. Cada ronda tendr\u00e1 cuatro reuniones de 5-10 minutos con otro\/a participante. Estas ser\u00e1n las rondas, y podr\u00e1s apuntarte a la que m\u00e1s te cuadre (o a todas si te animas <strong>\ud83e\udd20<\/strong>) visitando los enlaces:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>17:15-17:45 <a href=\"https:\/\/gatheround.com\/events\/w7K1kEQ064zqADndeAs6\"><strong>#Tarugobreaker21 \ud83c\udff8 Warm-up<\/strong><\/a><\/li><li>17:45-18:15 <a href=\"https:\/\/gatheround.com\/events\/nBIMrHtcbf3DPEwn2HpQ\"><strong>#Tarugobreaker21 \ud83d\udc7e Geek session<\/strong><\/a><\/li><li>18:15-18:45 <a href=\"https:\/\/gatheround.com\/events\/lhSLvJKQIieIcwcHVM2B\"><strong>After- #Tarugobreaker21 \ud83c\udf77<\/strong><\/a><\/li><\/ul>\n\n\n\n<p>La plataforma te har\u00e1 <em>match<\/em> de forma <em>random<\/em>, pero <strong>siempre priorizar\u00e1 emparejarte con personas con las que a\u00fan no hayas hablado, para fomentar nuevas conexiones<\/strong>.<\/p>\n\n\n\n<p>S\u00f3lo repetir\u00edas compa\u00f1ero\/a si, por motivos t\u00e9cnicos (internet d\u00e9bil) o humanos, os un\u00eds a varios juegos tarde. Esto se debe a que Gatheround va haciendo los match autom\u00e1ticamente de uno en uno.<\/p>\n\n\n\n<p>Lo que s\u00ed es seguro es que <strong>nunca jam\u00e1s os quedar\u00e9is colgados<\/strong>, sin nadie con quien hablar. \u00bfPor qu\u00e9? Porque los administradores de los juegos siempre seremos los \u00faltimos en ser emparejados, y s\u00f3lo si sois impares, para que nadie se quede en el limbo (tambi\u00e9n somos gente interesante con la que hablar \ud83d\ude1c).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo entro en la plataforma?<\/strong><\/h2>\n\n\n\n<p>Para participar, necesitas dos cosas: c\u00e1mara y micr\u00f3fono. Deber\u00e1s entrar en la p\u00e1gina <a rel=\"noreferrer noopener\" href=\"https:\/\/gatheround.com\/\" target=\"_blank\">https:\/\/gatheround.com\/<\/a> y darte de alta.<\/p>\n\n\n\n<p>Te recomendamos <strong>usar un nombre que te identifique claramente como asistente a la #Tarugo21<\/strong>. Primero, para que luego puedas consolidar las conexiones que hayas hecho buscando a tus interlocutores en el directorio del evento y poder escribirles o cerrar 1:1s con ellos. Segundo, porque si sospechamos que alguno de los participantes no tiene entrada, nos reservamos el derecho de poder cancelar su inscripci\u00f3n para priorizar a los tarugos que s\u00ed la tengan.<\/p>\n\n\n\n<p>Para ello, te pedir\u00e1 iniciar sesi\u00f3n:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tarugoconf.com\/blog\/wp-content\/uploads\/2021\/09\/image.png\" alt=\"Captura de Gatheround\" class=\"wp-image-5616\" width=\"398\" height=\"277\" srcset=\"https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image.png 795w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-300x209.png 300w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-768x535.png 768w\" sizes=\"auto, (max-width: 398px) 100vw, 398px\" \/><\/figure>\n\n\n\n<p>Una vez tengas usuario, s\u00f3lo tendr\u00e1s que ingresar en la p\u00e1gina de la ronda de <em>Tarugobreaker<\/em> que m\u00e1s te apetezca, \u00a1o a todas! Te recordamos aqu\u00ed los links para entrar en cada una:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>17:15-17:45 <a href=\"https:\/\/gatheround.com\/events\/w7K1kEQ064zqADndeAs6\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>#Tarugobreaker21 \ud83c\udff8 Warm-up<\/strong><\/a><\/li><li>17:45-18:15 <a href=\"https:\/\/gatheround.com\/events\/nBIMrHtcbf3DPEwn2HpQ\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>#Tarugobreaker21 \ud83d\udc7e Geek session<\/strong><\/a><\/li><li>18:15-18:45 <a href=\"https:\/\/gatheround.com\/events\/lhSLvJKQIieIcwcHVM2B\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>After- #Tarugobreaker21 \ud83c\udf77<\/strong><\/a><\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tarugoconf.com\/blog\/wp-content\/uploads\/2021\/09\/image-1.png\" alt=\"Captura de Gatheround\" class=\"wp-image-5617\" width=\"489\" height=\"628\" srcset=\"https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-1.png 652w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-1-234x300.png 234w\" sizes=\"auto, (max-width: 489px) 100vw, 489px\" \/><\/figure>\n\n\n\n<p>Te pedir\u00e1 que des permiso para acceder a tu c\u00e1mara y micr\u00f3fono, pues sin ellos no podr\u00e1s mantener llamadas con otros asistentes:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tarugoconf.com\/blog\/wp-content\/uploads\/2021\/09\/image-2-1024x906.png\" alt=\"Captura de Gatheround\" class=\"wp-image-5618\" width=\"512\" height=\"453\" srcset=\"https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-2-1024x906.png 1024w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-2-300x266.png 300w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-2-768x680.png 768w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-2-1536x1360.png 1536w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-2-1568x1388.png 1568w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-2.png 1707w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n\n\n\n<p>Una vez los des, \u00a1listo! Ya estar\u00e1s en la p\u00e1gina principal donde comenzar\u00e1n los juegos el jueves 21 (a la hora que corresponda) \ud83d\ude03. Tranquilidad, recordaremos los links de cada sesi\u00f3n en redes sociales y en Brella, para que no tengas que estar rebusc\u00e1ndolos el d\u00eda de la #Tarugo21 para entrar!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>FAQs<\/strong><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 pasa si tengo problemas t\u00e9cnicos?<\/strong><\/h4>\n\n\n\n<p>La mayor\u00eda de problemas t\u00e9cnicos en Gatheround se solucionan de tres maneras:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Cerrando otras apps de videoconferencia &#8211; por ejemplo, Zoom o Google Meets -.<\/li><li>Actualizando \/ reseteando tu navegador.<\/li><li>Probando con otro navegador o dispositivo.<\/li><\/ol>\n\n\n\n<p>Por otro lado, aqu\u00ed tienes <a href=\"https:\/\/intercom.help\/gatheround\/en\/collections\/2298787-troubleshooting\" target=\"_blank\" rel=\"noreferrer noopener\">una p\u00e1gina de problemas comunes<\/a> por si te pudiera ayudar. Si a\u00fan as\u00ed no funcionase, tenemos soporte a tiempo real pulsando este bot\u00f3n:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tarugoconf.com\/blog\/wp-content\/uploads\/2021\/09\/image-3-1024x882.png\" alt=\"Captura de Gatheround\" class=\"wp-image-5619\" width=\"512\" height=\"441\" srcset=\"https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-3-1024x882.png 1024w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-3-300x258.png 300w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-3-768x661.png 768w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-3.png 1031w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n\n\n\n<p>Os sugerimos que comprob\u00e9is si os funciona la c\u00e1mara y el micr\u00f3fono de manera previa al evento, y que hab\u00e9is otorgado permiso de acceso a ambos:<\/p>\n\n\n\n<p>En Chrome:<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/downloads.intercomcdn.com\/i\/o\/330867193\/096aabc66c63a4d3c440ba32\/group_27.png?expires=1619900122&amp;signature=16108aa70e207e71892a8936252bede2848d5b54c45d671681da5387a03dde29\" alt=\"Captura de Gatheround\" width=\"480\" height=\"459\"\/><\/figure>\n\n\n\n<p>O en Safari:<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/downloads.intercomcdn.com\/i\/o\/331525495\/6cdf236e01c5133eae423f70\/image.png?expires=1619900122&amp;signature=84a7a2d92cb5f0bcba2d866aa7921b895ef3102505c4e63224ee34f59da55953\" alt=\"Captura de Gatheround\" width=\"394\" height=\"276\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfPuedo saltarme una de las reuniones si no me apetece?<\/strong><\/h4>\n\n\n\n<p>Sin ning\u00fan problema. Puedes elegir saltarte una ronda d\u00e1ndole a \u00abI&#8217;d rather not share\u00bb y permanecer en la p\u00e1gina del grupo hasta la siguiente. Si alguien estuviera esperando un match, se te notificar\u00e1 por si te interesara unirte (o no) \ud83d\ude09.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/downloads.intercomcdn.com\/i\/o\/330828897\/ea9cebe8eeeb901b50dc17e8\/Screen+Shot+2021-04-29+at+4.45.39+PM.png?expires=1619901724&amp;signature=c5a1902fc1e95cb3371b8b7d40e96fce41207236c7caeeda806fee008e1c47c9\" alt=\"Captura de Gatheround\" width=\"744\" height=\"239\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfPuedo unirme sin v\u00eddeo?<\/strong><\/h4>\n\n\n\n<p>No. La idea es que se juegue en igualdad de condiciones y que se favorezca la fluidez en la comunicaci\u00f3n por lo que la comunicaci\u00f3n no verbal cobra bastante importancia.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfPuedo unirme aunque llegue tarde?<\/strong><\/h4>\n\n\n\n<p>Sin problema. Mientras haya alguien con quien emparejarte \ud83d\ude00. Lo \u00fanico, que el horario de cada ronda es fijo, por lo que tu tiempo de 1:1 se ver\u00e1 recortado, por lo que os sugerimos que se\u00e1is puntuales para que el networking sea enriquecedor y no se quede escaso.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo podr\u00e9 establecer contacto con los asistentes despu\u00e9s de la din\u00e1mica?<\/strong><\/h4>\n\n\n\n<p>Cuando los Tarugobreakers terminen, podr\u00e1s ver los matches que has tenido clickando en el s\u00edmbolo de chat de la esquina superior derecha de la p\u00e1gina. Ah\u00ed, podr\u00e1s enviarles mensajes directos. Si el\/la usuario\/a no estuviera ya disponible en la plataforma, se les notificar\u00e1 por email de que has querido establecer contacto \ud83d\ude09.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tarugoconf.com\/blog\/wp-content\/uploads\/2021\/09\/image-4-1024x513.png\" alt=\"Captura de Gatheround\" class=\"wp-image-5620\" width=\"512\" height=\"257\" srcset=\"https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-4-1024x513.png 1024w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-4-300x150.png 300w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-4-768x385.png 768w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2021\/09\/image-4.png 1366w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Entonces, \u00bftodo el mundo podr\u00e1 ver si estoy conectado\/a en tiempo real al Tarugobreaker?<\/strong><\/h4>\n\n\n\n<p>No, solo los organizadores tendr\u00e1n esa informaci\u00f3n. Mientras que s\u00ed se podr\u00e1 ver qui\u00e9nes se han apuntado, la informaci\u00f3n sobre tu disponibilidad a tiempo real est\u00e1 oculta a todos los participantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Utilizaremos la plataforma Gatheround, una especie de Chat Roulette para eventos que os emparejar\u00e1 de forma aleatoria con otros asistentes en reuniones 1:1 en las que se os sugerir\u00e1n temas constantemente como, por ejemplo, \u201c\u00bfcu\u00e1l es tu serie favorita?\u201d o \u201c\u00bfWozniak o Jobs?\u201d, para que nunca os qued\u00e9is sin saber de qu\u00e9 hablar. Para ello, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.trgcon.com\/blog\/tarugobreakers-tarugo21\/\" class=\"more-link\">Seguir leyendo<span class=\"screen-reader-text\"> \u00abLos Tarugobreakers de la #Tarugo21\u00bb<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":5625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[90,14,82],"class_list":["post-5615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-organizacion","tag-icebreakers","tag-networking","tag-tarugo21","entry"],"_links":{"self":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/5615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/comments?post=5615"}],"version-history":[{"count":4,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/5615\/revisions"}],"predecessor-version":[{"id":5626,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/5615\/revisions\/5626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/media\/5625"}],"wp:attachment":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/media?parent=5615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/categories?post=5615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/tags?post=5615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}