{"id":5438,"date":"2021-06-04T08:26:06","date_gmt":"2021-06-04T06:26:06","guid":{"rendered":"https:\/\/www.tarugoconf.com\/blog\/?p=5438"},"modified":"2021-06-04T08:26:08","modified_gmt":"2021-06-04T06:26:08","slug":"tarugo20-javi-santana","status":"publish","type":"post","link":"https:\/\/www.trgcon.com\/blog\/tarugo20-javi-santana\/","title":{"rendered":"Javi Santana en la #tarugo20: 20 a\u00f1os de desarrollo de software"},"content":{"rendered":"\n<p>Javi es conocido sobre todo por su paso por el BBVA, donde fue Data Services Lead, Javier Alois de Santana y Pobes -tal como consta en su DNI- <strong>tiene una larga trayectoria en el mundo del desarrollo de software en general y en el emprendimiento tecnol\u00f3gico en particular<\/strong>.<\/p>\n\n\n\n<p>Fund\u00f3 Agrogu\u00eda, una startup que ayudaba a los agricultores a optimizar la siembra y fumigaci\u00f3n de sus campos mediante GPS, hasta que esta fue adquirida. Fue fundador y CTO de CARTO, uno de los l\u00edderes mundiales en la gesti\u00f3n de datos geoespaciales. Despu\u00e9s de su paso por el BBVA se tom\u00f3 un a\u00f1o sab\u00e1tico para ense\u00f1ar a David Bonilla a conducir y consigui\u00f3 que este se sacara el carnet con 40 a\u00f1os. Despu\u00e9s de este extraordinario logro, ha fundado Tinybird.co que construye APIs para consultar zillones de registros en tiempo real en minutos en vez de semanas.<\/p>\n\n\n\n<p>Los inform\u00e1ticos hemos pasado en unos pocos a\u00f1os de semidioses que grababan sus programas -verdaderos haikus binarios- en tarjetas perforadas, a zangolotinos que necesitan una librer\u00eda de 10Mb para hacer un lpad.<\/p>\n\n\n\n<p>En esta charla, Javi hizo un repaso por <strong>la evoluci\u00f3n del desarrollo del software durante los \u00faltimos 20 a\u00f1os, con todos sus logros y -tambi\u00e9n- sus miserias<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"#tarugo20 - 20 a\u00f1os de desarrollo de software por Javi Santana\" src=\"https:\/\/player.vimeo.com\/video\/557618978?dnt=1&amp;app_id=122963\" width=\"640\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Puedes disfrutar el video siguiendo todas las diapos de la presentaci\u00f3n con total comodidad, o descargarlas y compartirlas:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-speaker-deck wp-block-embed-speaker-deck wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"#tarugo20 \/ Javi Santana \/ 20 a\u00f1os de desarrollo de software\" id=\"talk_frame_738630\" class=\"speakerdeck-iframe\" src=\"\/\/speakerdeck.com\/player\/5e431f5de7c343dc924f576e23ae8637\" width=\"640\" height=\"360\" style=\"aspect-ratio:640\/360; border:0; padding:0; margin:0; background:transparent;\" frameborder=\"0\" allowtransparency=\"true\" allowfullscreen=\"allowfullscreen\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Si te ha gustado la charla, no te cortes: puedes <a rel=\"noreferrer noopener\" href=\"https:\/\/twitter.com\/javisantana\" target=\"_blank\">felicitar a Jav<\/a><a href=\"https:\/\/twitter.com\/javisantana\" target=\"_blank\" rel=\"noreferrer noopener\">i<\/a><a rel=\"noreferrer noopener\" href=\"https:\/\/twitter.com\/javisantana\" target=\"_blank\"> en Twitter<\/a> y \u2013tambi\u00e9n\u2013 compartirla, para&nbsp;<strong>ayudar a que este mundo sea un poquito m\u00e1s tarugo que ayer, pero menos que ma\u00f1ana<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los inform\u00e1ticos hemos pasado en unos pocos a\u00f1os de semidioses que grababan sus programas -verdaderos haikus binarios- en tarjetas perforadas, a zangolotinos que necesitan una librer\u00eda de 10Mb para hacer un lpad.<br \/>\nEn esta charla, Javi hizo un repaso por la evoluci\u00f3n del desarrollo del software durante los \u00faltimos 20 a\u00f1os, con todos sus logros y -tambi\u00e9n- sus miserias.<\/p>\n","protected":false},"author":5,"featured_media":5451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[75,74,73,52],"class_list":["post-5438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-charlas","tag-informatica","tag-programacion","tag-software","tag-tarugo20","entry"],"_links":{"self":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/5438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/comments?post=5438"}],"version-history":[{"count":4,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/5438\/revisions"}],"predecessor-version":[{"id":5452,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/5438\/revisions\/5452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/media\/5451"}],"wp:attachment":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/media?parent=5438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/categories?post=5438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/tags?post=5438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}