{"id":5366,"date":"2020-09-22T11:28:03","date_gmt":"2020-09-22T09:28:03","guid":{"rendered":"https:\/\/www.tarugoconf.com\/blog\/?p=5366"},"modified":"2020-10-13T15:48:53","modified_gmt":"2020-10-13T13:48:53","slug":"el-tarugobreaker-el-icebreaker-de-la-tarugo20","status":"publish","type":"post","link":"https:\/\/www.trgcon.com\/blog\/el-tarugobreaker-el-icebreaker-de-la-tarugo20\/","title":{"rendered":"El Tarugobreaker: el icebreaker de la #Tarugo20"},"content":{"rendered":"\n<p>Utilizaremos la plataforma <a href=\"https:\/\/icebreaker.video\/\">icebreaker.video<\/a>, una especie de <em>Chat Roulette <\/em>para eventos que <strong>os emparejar\u00e1 de forma aleatoria con otr@s asistentes en reuniones 1:1 en las que se os sugerir\u00e1n temas constantemente<\/strong> como, por ejemplo, \u201c\u00bfcu\u00e1l es tu serie favorita?\u201d o \u201c\u00bfWozniak o Jobs?\u201d, para que nunca os qued\u00e9is sin saber de qu\u00e9 hablar.<\/p>\n\n\n\n<p>Para ello, debes darte de alta ASAP en la p\u00e1gina de la Tarugo en Icebreaker (tienes los enlaces a cada una de las rondas m\u00e1s adelante). \u00bfPor qu\u00e9 lo antes posible? Porque tenemos un l\u00edmite de 200 participantes en el juego AL MISMO TIEMPO.<\/p>\n\n\n\n<p>El Icebreaker de la Tarugo constar\u00e1 de tres rondas de 30 minutos cada una (20 de juego y 10 de margen con la siguiente, para que pod\u00e1is ir al servicio o a la nevera). Cada ronda tendr\u00e1 cuatro reuniones de 5 minutos con otro\/a participante. Estas ser\u00e1n las rondas, y podr\u00e1s apuntarte a la que m\u00e1s te cuadre (o a todas si te animas <strong>\ud83e\udd20<\/strong>) visitando los enlaces:<\/p>\n\n\n\n<p class=\"has-text-align-center\">De 17:15 a 17:45 <a href=\"https:\/\/icebreaker.video\/events\/DLAVB18dFUnhhTguUL5x\"><strong>Tarugobreaker \ud83c\udfd3 Warm Up<\/strong><\/a><br>De 17:45 a 18:15 <a href=\"https:\/\/icebreaker.video\/events\/WiiLZR2jCoSEXCYpkorq\"><strong>Super-Tarugobreaker&nbsp; \ud83e\uddb8\u200d\u2640\ufe0f\ud83e\uddb8\u200d\u2642\ufe0f<\/strong><\/a><br>De 18:15 a 18:45 <a href=\"https:\/\/icebreaker.video\/events\/s1loif872VBm5jvxQe8G\"><strong>Tarugobreaker de After \ud83e\udd20<\/strong><\/a><\/p>\n\n\n\n<p>La plataforma te har\u00e1 <em>match<\/em> de forma <em>random<\/em>, pero <strong>siempre priorizar\u00e1 emparejarte con personas con las que a\u00fan no hayas hablado, para fomentar nuevas conexiones<\/strong>.<\/p>\n\n\n\n<p>S\u00f3lo repetir\u00edas compa\u00f1ero\/a si, por motivos t\u00e9cnicos (internet d\u00e9bil) o humanos, os un\u00eds a varios juegos tarde. Esto se debe a que icebreaker.video va haciendo los match autom\u00e1ticamente de uno en uno.<\/p>\n\n\n\n<p>Lo que s\u00ed es seguro es que <strong>nunca jam\u00e1s os quedar\u00e9is colgados<\/strong>, sin nadie con quien hablar. \u00bfPor qu\u00e9? Porque los administradores de los juegos siempre seremos los \u00faltimos en ser emparejados, y s\u00f3lo si sois impares, para que nadie se quede en el limbo (tambi\u00e9n somos gente interesante con la que hablar \ud83d\ude1c).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo entro en la plataforma?<\/strong><\/h2>\n\n\n\n<p>Para participar, necesitas tres cosas: C\u00e1mara, micr\u00f3fono y una cuenta de Google. Deber\u00e1s entrar en la p\u00e1gina<a href=\"https:\/\/icebreaker.video\/\"> https:\/\/icebreaker.video\/<\/a> y darte de alta.<\/p>\n\n\n\n<p>Te recomendamos <strong>usar un nombre que te identifique claramente como asistente a la #Tarugo20<\/strong>. Primero, para que luego puedas consolidar las conexiones que hayas hecho buscando a tus interlocutores en el directorio del evento y poder escribirles o cerrar 1:1s con ellos. Segundo, porque si sospechamos que alguno de los participantes no es asistente de la #tarugo20, nos reservamos el derecho de poder cancelar su inscripci\u00f3n para priorizar a los tarugos con entrada.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/6aGIIDkdoLSHV6vmd0koqPadHmmQo4Q8VBXwnx3jjZO6vX1VTuKduf_OQ8uqdNEBjlVGiTgUGE-wmnaR9EBSd227dOOPTFgBTFCJ1cz4mNoTxez8Ckz4g4V2klBdVLpk6xiCAr98\" alt=\"\" width=\"800\" height=\"360\"\/><\/figure>\n\n\n\n<p>Para ello, te pedir\u00e1 iniciar sesi\u00f3n con Google:<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/NuwgelDyXL149l4-7CJn7CMHP3HAfCI0Qk42c8ITPoCENQL3qLHHtEwgA16b4wflWgzbQCBAkH54w6LU8CbmaSy-GMa4LfC3X_liML2PdIzJOq8YfwfiYiJjttG070AQVFCOBDyZ\" alt=\"\" width=\"346\" height=\"257\"\/><\/figure>\n\n\n\n<p>Una vez tengas usuario, s\u00f3lo tendr\u00e1s que ingresar en la p\u00e1gina de la ronda de <em>Tarugobreaker<\/em> que m\u00e1s te apetezca, \u00a1o a todas! Te recordamos aqu\u00ed los links para entrar en cada una:<\/p>\n\n\n\n<p>De 17:15 a 17:45 <a href=\"https:\/\/icebreaker.video\/events\/DLAVB18dFUnhhTguUL5x\"><strong>Tarugobreaker \ud83c\udfd3 Warm Up<\/strong><\/a><br>De 17:45 a 18:15 <a href=\"https:\/\/icebreaker.video\/events\/WiiLZR2jCoSEXCYpkorq\"><strong>Super-Tarugobreaker\u00a0 \ud83e\uddb8\u200d\u2640\ufe0f\ud83e\uddb8\u200d\u2642\ufe0f<\/strong><\/a><br>De 18:15 a 18:45 <a href=\"https:\/\/icebreaker.video\/events\/s1loif872VBm5jvxQe8G\"><strong>Tarugobreaker de After \ud83e\udd20<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tarugoconf.com\/blog\/wp-content\/uploads\/2020\/10\/image.png\" alt=\"\" class=\"wp-image-5385\" width=\"363\" height=\"542\" srcset=\"https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2020\/10\/image.png 589w, https:\/\/www.trgcon.com\/blog\/wp-content\/uploads\/2020\/10\/image-201x300.png 201w\" sizes=\"auto, (max-width: 363px) 100vw, 363px\" \/><\/figure>\n\n\n\n<p>Te pedir\u00e1 que des permiso para acceder a tu c\u00e1mara y micr\u00f3fono, pues sin ellos no podr\u00e1s mantener llamadas con otr@s asistentes:<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/rpg9hgYq85t0KMBmnFV16c6FKpioLdKwd3K1e1tZGomKqrakcCbipP5UAgozeiQ3Th6sKpPExDDmbnd-sio30cYsoWACL6R6Z7K2jHFEUevYlS4RRnOkaFHkLC4dLR1ngGgVAFfw\" alt=\"\" width=\"395\" height=\"297\"\/><\/figure>\n\n\n\n<p>Una vez los des, \u00a1listo! Ya estar\u00e1s en la p\u00e1gina principal donde comenzar\u00e1n los juegos el jueves 26 (a la hora que corresponda) \ud83d\ude03. Tranquil@, recordaremos los links de cada sesi\u00f3n en redes sociales y en Brella, para que no tengas que estar rebusc\u00e1ndolos el d\u00eda de la #Tarugo20 para entrar!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>FAQs<\/strong><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 pasa si tengo problemas t\u00e9cnicos?<\/strong><\/h4>\n\n\n\n<p>La mayor\u00eda de problemas t\u00e9cnicos en icebreaker.video se solucionan de tres maneras:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Cerrando otras apps de videoconferencia &#8211; por ejemplo, Zoom o Google Meets -.<\/li><li>Actualizando \/ reseteando tu navegador.<\/li><li>Probando con otro navegador o dispositivo.<\/li><\/ol>\n\n\n\n<p>Por otro lado,<a href=\"https:\/\/intercom.help\/icebreaker\/en\/collections\/2298787-troubleshooting\"> aqu\u00ed tienes una p\u00e1gina de errores comunes<\/a> por si te pudiera ayudar. Si a\u00fan as\u00ed no funcionase, tenemos soporte a tiempo real pulsando este bot\u00f3n:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/_TreNPtMXku-uMwMCei2dTOOEbfEJSWKwcDS-nk25gXjQuuRHVvt9ArfNu32n_BXZUOkEsyDPrtiR2UA1zDBhUSkl6ukyPHDMH3avMrEWbd4DtWBjbsG-nfHGJjgM6W777Z_qVV-\" alt=\"\"\/><\/figure>\n\n\n\n<p>Os sugerimos que comprob\u00e9is si os funciona la c\u00e1mara y el micr\u00f3fono de manera previa al evento, y que hab\u00e9is otorgado permiso de acceso a ambos:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/DOBvICDKXbxmhDNdnp2g8KkHGfnJygjkUecZjBrk1Mb7k0Tm54FKmB6-WpgRk7LjERUS9FH-wWXWaXUijTfztvw7ibXsRNSbcA-f5shoiqH5EX2KEnSUtvjno4XmzWfItP46d7Bl\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/yN9ZkSpl2xTruR4lSIysmT0b9koXyHez22pYgYOGUk_0waBu0F3bwJRxgz9ziyQ-d6WV0aVpAKKPM2lTX_HQp9SdJS-WZ50EuSPNzpCrVRS_tSl17gtZZn-jV4dtVdD8-2MZ8g6a\" alt=\"\" width=\"800\" height=\"681\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfPuedo saltarme una de las cuatro reuniones si no me apetece?<\/strong><\/h4>\n\n\n\n<p>Sin ning\u00fan problema. Puedes elegir saltarte una ronda y permanecer en la p\u00e1gina del grupo hasta la siguiente. Si alguien estuviera esperando un match, se te notificar\u00e1 por si te interesara unirte (o no) \ud83d\ude09.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/f_RM6TYXMJ8TvgM9F6v0iHQ78Vfv_CyEuJsYT3Ni-eDyDpBvd__mRBtUYT7vc_X_Cz2l2f2J8p8X0eY2nn2TNByJk6lBLxz1hpuyRV3kG8OxXKEHYB7s5s1VlJ1oJWAUbywz006F\" alt=\"\" width=\"640\" height=\"330\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/vu4i5ZiiRSXyrJNLq1y88E4EO_HDElAzVp43FQP2sINV_sDmtn9a3VMkXGT4Kkhl49X1ngvqo0MxNTGK2UECI5XtFml28VDNPMDEOIRK1Ja7Qvz9taRNhjNrOGQiL3y63FFymtBp\" alt=\"\" width=\"680\" height=\"189\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfPuedo unirme sin v\u00eddeo?<\/strong><\/h4>\n\n\n\n<p>No. La idea es que se juegue en igualdad de condiciones y que se favorezca la fluidez en la comunicaci\u00f3n por lo que la comunicaci\u00f3n no verbal cobra bastante importancia.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfPuedo unirme aunque llegue tarde?<\/strong><\/h4>\n\n\n\n<p>Sin problema. Mientras haya alguien con quien emparejarte \ud83d\ude00. Lo \u00fanico, que el horario de cada ronda es fijo, por lo que tu tiempo de 1:1 se ver\u00e1 recortado, por lo que os sugerimos que se\u00e1is puntuales para que el networking sea enriquecedor y no se quede escaso.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo podr\u00e9 establecer contacto con los asistentes despu\u00e9s de la din\u00e1mica?<\/strong><\/h4>\n\n\n\n<p>Cuando los Icebreakers terminen, podr\u00e1s ver los matches que has tenido clickando en el s\u00edmbolo de chat de la esquina superior derecha de la p\u00e1gina. Ah\u00ed, podr\u00e1s enviarles mensajes directos. Si el\/la usuario\/a no estuviera ya disponible en la plataforma, se les notificar\u00e1 por email de que has querido establecer contacto \ud83d\ude09.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/nkQHGAsMCxchxpo6eMQMnZn6T0629MmI7NGLVGtxuIJyXku3N_RHwqjzdV43Ioqq5k4h63z4ir4h4wjA5ZjyX2ndNK_5zpjXxdzhmkzOGIQHfTc1w2G17VHjmtW1XtL4t5lx_Szg\" alt=\"\" width=\"800\" height=\"83\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Entonces, \u00bftodo el mundo podr\u00e1 ver si estoy conectado\/a en tiempo real al Icebreaker?<\/strong><\/h4>\n\n\n\n<p>No, s\u00f3lo los organizadores tendr\u00e1n esa informaci\u00f3n. Mientras que s\u00ed se podr\u00e1 ver qui\u00e9nes se han apuntado, la informaci\u00f3n sobre tu disponibilidad a tiempo real est\u00e1 oculta a todos l@s participantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Utilizaremos la plataforma icebreaker.video, una especie de Chat Roulette para eventos que os emparejar\u00e1 de forma aleatoria con otr@s asistentes en reuniones 1:1 en las que se os sugerir\u00e1n temas constantemente como, por ejemplo, \u201c\u00bfcu\u00e1l es tu serie favorita?\u201d o \u201c\u00bfWozniak o Jobs?\u201d, para que nunca os qued\u00e9is sin saber de qu\u00e9 hablar. Para ello, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.trgcon.com\/blog\/el-tarugobreaker-el-icebreaker-de-la-tarugo20\/\" class=\"more-link\">Seguir leyendo<span class=\"screen-reader-text\"> \u00abEl Tarugobreaker: el icebreaker de la #Tarugo20\u00bb<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5366","post","type-post","status-publish","format-standard","hentry","category-uncategorized","entry"],"_links":{"self":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/5366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/comments?post=5366"}],"version-history":[{"count":14,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/5366\/revisions"}],"predecessor-version":[{"id":5386,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/5366\/revisions\/5386"}],"wp:attachment":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/media?parent=5366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/categories?post=5366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/tags?post=5366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}