{"id":4395,"date":"2016-08-25T09:14:05","date_gmt":"2016-08-25T07:14:05","guid":{"rendered":"http:\/\/www.tarugoconf.com\/fiesta-taruga-2016\/"},"modified":"2016-08-25T09:14:05","modified_gmt":"2016-08-25T07:14:05","slug":"fiesta-taruga-2016","status":"publish","type":"post","link":"https:\/\/www.trgcon.com\/blog\/fiesta-taruga-2016\/","title":{"rendered":"La Fiesta Taruga"},"content":{"rendered":"<p>Ya disponemos de todos los detalles de la <strong>Fiesta Taruga<\/strong>, donde todos los asistentes a la Tarugoconf podr\u00e1n festejar el \u00e9xito del evento&#8230; o intentar olvidar el fracaso del mismo.<\/p>\n<p>Se celebrar\u00e1 en el <a href=\"http:\/\/cafedelriomadrid.com\/\">Caf\u00e9 del R\u00edo<\/a> -enclave privilegiado con una de las mejores vistas de Madrid- <strong>de 20:00h a 22:00h<\/strong>, justo despu\u00e9s de la Tarugoconf.<\/p>\n<p>En el Caf\u00e9 del R\u00edo, dispondremos en exclusiva del mirador -la terraza superior- donde disfrutaremos de <strong>dos horas de barra libre de vino, cervezas y refrescos<\/strong>.<\/p>\n<p><img decoding=\"async\" src=\"\/blog\/content\/images\/2016\/08\/27297.jpg\" alt=\"Vistas desde el Caf\u00e9 del R\u00edo\"><\/p>\n<p><img decoding=\"async\" src=\"\/blog\/content\/images\/2016\/08\/tarugoconf-fiesta-taruga-exterior-peq.jpg\" alt=\"El Caf\u00e9 del R\u00edo\"><\/p>\n<p><img decoding=\"async\" src=\"\/blog\/content\/images\/2016\/08\/27232.jpg\" alt=\"Evento en el Caf\u00e9 del R\u00edo\"><\/p>\n<p>Adem\u00e1s, contaremos con un <strong>men\u00fa compuesto por 24 pinchos por persona<\/strong> -dos de cada tipo: 5 frios, 5 calientes y 2 postres- donde todo el mundo podr\u00e1 encontrar algo que le guste, incluso veganos y caballeros Jedi.<\/p>\n<p><img decoding=\"async\" src=\"\/blog\/content\/images\/2016\/08\/menu-fiesta-taruga.jpg\" alt=\"Men\u00fa en el Caf\u00e9 del R\u00edo\"><\/p>\n<p>Las vistas son geniales, el men\u00fa <em>prometedor<\/em>, pero hemos escogido el Caf\u00e9 del R\u00edo, sobre todo, porque <strong>est\u00e1 a 10 minutos andando desde el Campus Madrid<\/strong>, el sitio donde se celebrar\u00e1 la Tarugoconf.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m27!1m12!1m3!1d3037.7422700519915!2d-3.7234199843143534!3d40.41455997936542!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!4m12!3e2!4m5!1s0xd422875fe8d546d%3A0xfc628be71587461f!2sCampus+Madrid%2C+Calle+Moreno+Nieto%2C+Madrid!3m2!1d40.4124188!2d-3.7182578!4m4!1s0x0%3A0x4823b391a4d43c3e!3m2!1d40.4169473!2d-3.7232412999999998!5e0!3m2!1ses!2ses!4v1472113472885\" width=\"600\" height=\"450\" frameborder=\"0\" style=\"border:0\" allowfullscreen=\"\"><\/iframe><\/p>\n<p>Por temas de aforo, el Mirador se cerrar\u00e1 en exclusiva para los tarugos, as\u00ed que <strong>ser\u00e1 imprescindible contar con la acreditaci\u00f3n del evento para poder acceder<\/strong> al mismo, no os la com\u00e1is \u00a1Os esperamos a todos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya disponemos de todos los detalles de la Fiesta Taruga, donde todos los asistentes a la Tarugoconf podr\u00e1n festejar el \u00e9xito del evento&#8230; o intentar olvidar el fracaso del mismo. Se celebrar\u00e1 en el Caf\u00e9 del R\u00edo -enclave privilegiado con una de las mejores vistas de Madrid- de 20:00h a 22:00h, justo despu\u00e9s de la &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.trgcon.com\/blog\/fiesta-taruga-2016\/\" class=\"more-link\">Seguir leyendo<span class=\"screen-reader-text\"> \u00abLa Fiesta Taruga\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":4455,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[16],"class_list":["post-4395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-fiesta","entry"],"_links":{"self":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/4395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/comments?post=4395"}],"version-history":[{"count":1,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/4395\/revisions"}],"predecessor-version":[{"id":4456,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/4395\/revisions\/4456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/media\/4455"}],"wp:attachment":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/media?parent=4395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/categories?post=4395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/tags?post=4395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}