{"id":4391,"date":"2016-06-30T15:49:00","date_gmt":"2016-06-30T13:49:00","guid":{"rendered":"http:\/\/www.tarugoconf.com\/tarugoconf-familia\/"},"modified":"2016-06-30T15:49:00","modified_gmt":"2016-06-30T13:49:00","slug":"tarugoconf-familia","status":"publish","type":"post","link":"https:\/\/www.trgcon.com\/blog\/tarugoconf-familia\/","title":{"rendered":"Ven a la Tarugoconf con la familia"},"content":{"rendered":"<p><mark>UPDATE (26\/AGO\/2016): Precios, men\u00fas y actividades definitivas<\/mark><\/p>\n<p>La agenda de nuestro evento es tan awes\u00f3mica que la mayor\u00eda de la gente ni siquiera se ha percatado de que <strong>la Tarugoconf no dura un d\u00eda, sino dos<\/strong>.<\/p>\n<p><img decoding=\"async\" src=\"\/blog\/content\/images\/2016\/06\/sabado-tarugo.jpg\" alt=\"S\u00e1bado Tarugo\"><\/p>\n<p>Si, el viernes es el d\u00eda principal del evento, pero pensando en la gente de fuera que se acerque a Madrid; y en todos los tarugos que quieran asistir, pero no puedan conseguir una de las pocas entradas a la venta, celebraremos un <strong>s\u00e1bado tarugo<\/strong>.<\/p>\n<h2 id=\"elsbadotarugo\">El s\u00e1bado tarugo<\/h2>\n<p>El s\u00e1bado tarugo es una <strong>actividad de <em>networking<\/em> familiar, opcional y complementaria<\/strong> a las actividades principales del evento.<\/p>\n<ul>\n<li>Puede venir quien quiera, haya estado en el evento o no.<\/li>\n<li>Puede traer a quien quiera: pareja, amigos, ni\u00f1os&#8230;<\/li>\n<li>Si, la actividad es completa y absolutamente <em>ni\u00f1os friendly<\/em><\/li>\n<li>Si alguien quiere asistir s\u00f3lo debe enviarnos un correo, hasta 2 semanas antes del evento, a <a href=\"mailto:tarugoconf@bonillaware.com\">tarugoconf@bonillaware.com<\/a>, avisandonos del n\u00famero de plazas que quiere reservar.<\/li>\n<li><strong>El precio es de 35\u20ac por adulto<\/strong> e incluye entrada al museo y <mark>COMIDA PANTAGRU\u00c9LICA<\/mark> que detallaremos a continuaci\u00f3n. <strong>Los ni\u00f1os pagar\u00e1n 27\u20ac<\/strong>, que le dar\u00e1 derecho a disfrutar de la misma visita al museo, un m\u00e1s comedido men\u00fa infantil y <mark>pase de Parque de Atracciones para todo el d\u00eda<\/mark>.<\/li>\n<\/ul>\n<h2 id=\"agenda\">Agenda<\/h2>\n<ul>\n<li><strong>11:00h -Visita al MUNCYT (Museo Nacional de Ciencia y Tecnolog\u00eda)<\/strong>. Un museo que est\u00e1 en Alcobendas, pero que tiene una parada de Metro (Marqu\u00e9s de la Valdivia) a 300m. All\u00ed disfrutaremos de varias actividades -visita guiada, show en el planetario- que depender\u00e1n del tama\u00f1o final del grupo.<br \/>\n<img decoding=\"async\" src=\"http:\/\/www.tarugoconf.com\/assets\/img\/agenda\/muncyt.png\" alt=\"MUNCYT\"><\/li>\n<li><strong>13:15 &#8211; Salida hacia la Moraleja Green.<\/strong> Los que no vayamos en coche iremos juntos, en Metro, linea directa y apenas dos paradas. <em>Facile e Divertente!<\/em><\/li>\n<li><strong>13:30h &#8211; Llegada a la Moraleja Green<\/strong>. Un centro comercial que tiene al lado un prado enorme, con un mont\u00f3n de atracciones para cr\u00edos y un lago en medio, todo rodeado de bastantes restaurantes desde donde puedes ver a los ni\u00f1os jugar sin riesgo.<img decoding=\"async\" src=\"http:\/\/www.tarugoconf.com\/assets\/img\/agenda\/moraeja-green.jpg\" alt=\"Moraleja Green\"><\/li>\n<\/ul>\n<h2 id=\"lacomida\">La Comida<\/h2>\n<p>A partir de las 13:30h, disfrutaremos del siguiente men\u00fa en el <a href=\"http:\/\/estrelladegalicia.es\/local\/moraleja\/\">restaurante Estrella Galicia<\/a> de La Moraleja Green:<\/p>\n<ul>\n<li>ENTRANTES (3 raciones para cada 4 personas): Wok de verduras con San Sim\u00f3n y Soja, Raciones de croquetas caseras, Bu\u00f1uelos de bacalao con Alioli, Raciones de jam\u00f3n ib\u00e9rico y queso S. Sim\u00f3n<\/li>\n<li>PLATO PRINCIPAL: A elegir entre <strong>sepia a la plancha con cachelos<\/strong> o <strong>Ternera gallega asada tradicional<\/strong>.<\/li>\n<\/ul>\n<p>Tambi\u00e9n est\u00e1 incluido un surtido de postres y 3 bebidas por persona (cerveza, vino o refrescos).<\/p>\n<p><strong>Los ni\u00f1os contar\u00e1n con un men\u00fa infantil<\/strong> compuesto de <em>nuggets<\/em>, patatas y huevo frito y, de postre, helado.<\/p>\n<h2 id=\"elparquedeatracciones\">El Parque de Atracciones<\/h2>\n<p>Los ni\u00f1os podr\u00e1n montar en todas las atracciones de <a href=\"http:\/\/www.moralejaventura.com\/\">Moraleja Aventura<\/a> -un peque\u00f1o parque de atracciones- todas las veces que quieran, mientras los adultos <del>les vigilan<\/del> descansan en los bares de alrededor.<\/p>\n<p>Recuerda, si quieres asistir debes enviarnos un correo a <a href=\"mailto:tarugoconf@bonillaware.com\">tarugoconf@bonillaware.com<\/a>, avisandonos del n\u00famero de plazas que quieres reservar.<\/p>\n<p><mark>PS: Debido a la fama de algunos tarugos, los <em>gin tonics<\/em> y dem\u00e1s bebidas espirituosas post-comida NO est\u00e1n incluidas en el precio de la actividad<\/mark><\/p>\n","protected":false},"excerpt":{"rendered":"<p>UPDATE (26\/AGO\/2016): Precios, men\u00fas y actividades definitivas La agenda de nuestro evento es tan awes\u00f3mica que la mayor\u00eda de la gente ni siquiera se ha percatado de que la Tarugoconf no dura un d\u00eda, sino dos. Si, el viernes es el d\u00eda principal del evento, pero pensando en la gente de fuera que se acerque &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.trgcon.com\/blog\/tarugoconf-familia\/\" class=\"more-link\">Seguir leyendo<span class=\"screen-reader-text\"> \u00abVen a la Tarugoconf con la familia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":4463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[13,14],"class_list":["post-4391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-familia","tag-networking","entry"],"_links":{"self":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/4391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/comments?post=4391"}],"version-history":[{"count":1,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/4391\/revisions"}],"predecessor-version":[{"id":4464,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/posts\/4391\/revisions\/4464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/media\/4463"}],"wp:attachment":[{"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/media?parent=4391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/categories?post=4391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trgcon.com\/blog\/wp-json\/wp\/v2\/tags?post=4391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}